{"id":2739,"count":63,"description":"","link":"https:\/\/livingstonepartners.com\/de\/category\/news\/","name":"Nachrichten aus dem Unternehmen","slug":"news","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachrichten aus dem Unternehmen Archives - Livingstone Partners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livingstonepartners.com\/de\/category\/news\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachrichten aus dem Unternehmen Archives - Livingstone Partners\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livingstonepartners.com\/de\/category\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Livingstone Partners\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/category\\\/news\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/category\\\/news\\\/\",\"name\":\"Nachrichten aus dem Unternehmen Archives - Livingstone Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/category\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/category\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insights\",\"item\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/insights\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nachrichten aus dem Unternehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/\",\"name\":\"Livingstone Partners\",\"description\":\"Deals Done Right.\",\"publisher\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#organization\",\"name\":\"Livingstone Partners\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"contentUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"caption\":\"Livingstone Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachrichten aus dem Unternehmen Archives - Livingstone Partners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livingstonepartners.com\/de\/category\/news\/","og_locale":"de_DE","og_type":"article","og_title":"Nachrichten aus dem Unternehmen Archives - Livingstone Partners","og_url":"https:\/\/livingstonepartners.com\/de\/category\/news\/","og_site_name":"Livingstone Partners","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/livingstonepartners.com\/de\/category\/news\/","url":"https:\/\/livingstonepartners.com\/de\/category\/news\/","name":"Nachrichten aus dem Unternehmen Archives - Livingstone Partners","isPartOf":{"@id":"https:\/\/livingstonepartners.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/livingstonepartners.com\/de\/category\/news\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/livingstonepartners.com\/de\/category\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/livingstonepartners.com\/de\/"},{"@type":"ListItem","position":2,"name":"Insights","item":"https:\/\/livingstonepartners.com\/de\/insights\/"},{"@type":"ListItem","position":3,"name":"Nachrichten aus dem Unternehmen"}]},{"@type":"WebSite","@id":"https:\/\/livingstonepartners.com\/de\/#website","url":"https:\/\/livingstonepartners.com\/de\/","name":"Livingstone Partners","description":"Deals Done Right.","publisher":{"@id":"https:\/\/livingstonepartners.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livingstonepartners.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/livingstonepartners.com\/de\/#organization","name":"Livingstone Partners","url":"https:\/\/livingstonepartners.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/livingstonepartners.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","contentUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","caption":"Livingstone Partners"},"image":{"@id":"https:\/\/livingstonepartners.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/categories\/2739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/posts?categories=2739"},{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/insights?categories=2739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}