{"id":1336,"date":"2026-05-05T14:15:58","date_gmt":"2026-05-05T18:15:58","guid":{"rendered":"https:\/\/livingstagenew.wpenginepowered.com\/team-member\/andrew-bozzelli-de\/"},"modified":"2026-05-06T09:27:34","modified_gmt":"2026-05-06T13:27:34","slug":"andrew-bozzelli","status":"publish","type":"team-member","link":"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/","title":{"rendered":"Andrew Bozzelli"},"content":{"rendered":"\n<p>Andy kam 2009 zu Livingstone und ist Co-Leiter der Business &amp; Technology Services-Praxis von Livingstone, die Kunden bei der Entwicklung, Bewertung und Durchf\u00fchrung von M&amp;A-, Refinanzierungs- und Umstrukturierungstransaktionen in verschiedenen Endm\u00e4rkten unterst\u00fctzt. Er verf\u00fcgt \u00fcber 20 Jahre Erfahrung in der Transaktions- und Finanzberatung, einschlie\u00dflich grenz\u00fcberschreitender Fusionen und \u00dcbernahmen auf der Verk\u00e4ufer- und K\u00e4uferseite, der Beschaffung von Eigen- und Fremdkapital sowie in Sondersituationen (\u00a7363-Verk\u00e4ufe, Artikel 9-Verk\u00e4ufe und staatliche Zwangsverwaltung). Er hat globale strategische Unternehmen, f\u00fchrende Private-Equity-Firmen, Risikokapitalfirmen, Family Offices und Gr\u00fcnder-\/Familien-\/unternehmergef\u00fchrte Unternehmen beraten und Transaktionen mit ihnen durchgef\u00fchrt.<\/p>\n<p>Andys umfassende Branchenabdeckung umfasst Software, Sicherheit, Information, Vertrieb und technologiegest\u00fctzte Dienste. Er hat mit vielen der f\u00fchrenden strategischen K\u00e4ufer in diesen Sektoren Gesch\u00e4fte gemacht und pflegt pers\u00f6nliche Beziehungen zu f\u00fchrenden mittelst\u00e4ndischen Finanzinvestoren. Dar\u00fcber hinaus hat Andy Kunden aus den Bereichen Verbraucher, Gesundheitswesen und Industrie beraten.<\/p>\n<p>Andy sitzt im Vorstand der gemeinn\u00fctzigen Organisation <a href=\"https:\/\/www.imaginationtheater.org\/\">Imagination Theater<\/a>, die einem vielf\u00e4ltigen Publikum originelle, dynamische und partizipative Theaterprogramme bietet, die das Wohlbefinden steigern und eine b\u00fcrgerlichere, sicherere Gesellschaft schaffen.<\/p>\n<p>Andy wurde in M&amp;A-Publikationen zitiert, darunter MergerMarket und The Deal Magazine. Er war au\u00dferdem Gastredner an der Booth School of Business der University of Chicago, der Kellogg School of Management der Northwestern University, der Northwestern Pritzker School of Law, dem Mendoza College of Business der University of Notre Dame und bei verschiedenen Panels zu M&amp;A-Themen.<\/p>\n<p>Vor Livingstone war Andy als Steuermanager bei KPMG t\u00e4tig, wo er f\u00fcnf Jahre lang zu Steuerkonformit\u00e4t und Fragen im Zusammenhang mit US-amerikanischen und internationalen Aktien- und Schuldeninvestitionen beriet. Er ist zertifizierter Wirtschaftspr\u00fcfer.<\/p>\n<p>Andy lebt mit seiner Frau, seinen beiden S\u00f6hnen, seiner Tochter und seinem Hund im Stadtteil Roscoe Village in Chicago. Er stammt urspr\u00fcnglich aus Rochester, NY.<\/p>\n<p><strong>Ausbildung:<\/strong><\/p>\n<ul>\n<li>MBA, Universit\u00e4t Chicago<\/li>\n<li>MS und BBA, University of Notre Dame<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"job-title":[166],"office":[],"sector":[719],"service":[443],"class_list":["post-1336","team-member","type-team-member","status-publish","hentry","job-title-executive-assistant-de","sector-generation-assets-renewables-upstream","service-debt-advisory"],"acf":{"headshot":60833,"headshot_alt":60834,"position":1,"job_title":170,"offices":[294],"email":"bozzelli@livingstonepartners.com","phone":"+1 312 670 5924","mobile_phone":"+1 312 532 2873","connect":"https:\/\/www.linkedin.com\/in\/bozzelli\/","sectors":[691,692],"services":[442,441]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Andrew Bozzelli - Livingstone Partners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andrew Bozzelli - Livingstone Partners\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/\" \/>\n<meta property=\"og:site_name\" content=\"Livingstone Partners\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T13:27:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/team-member\\\/andrew-bozzelli\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/team-member\\\/andrew-bozzelli\\\/\",\"name\":\"Andrew Bozzelli - Livingstone Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#website\"},\"datePublished\":\"2026-05-05T18:15:58+00:00\",\"dateModified\":\"2026-05-06T13:27:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/team-member\\\/andrew-bozzelli\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/team-member\\\/andrew-bozzelli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/team-member\\\/andrew-bozzelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team Members\",\"item\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/team-member\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Andrew Bozzelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/\",\"name\":\"Livingstone Partners\",\"description\":\"Deals Done Right.\",\"publisher\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#organization\",\"name\":\"Livingstone Partners\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"contentUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"caption\":\"Livingstone Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Andrew Bozzelli - Livingstone Partners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/","og_locale":"de_DE","og_type":"article","og_title":"Andrew Bozzelli - Livingstone Partners","og_url":"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/","og_site_name":"Livingstone Partners","article_modified_time":"2026-05-06T13:27:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/","url":"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/","name":"Andrew Bozzelli - Livingstone Partners","isPartOf":{"@id":"https:\/\/livingstonepartners.com\/de\/#website"},"datePublished":"2026-05-05T18:15:58+00:00","dateModified":"2026-05-06T13:27:34+00:00","breadcrumb":{"@id":"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/livingstonepartners.com\/de\/team-member\/andrew-bozzelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/livingstonepartners.com\/de\/"},{"@type":"ListItem","position":2,"name":"Team Members","item":"https:\/\/livingstonepartners.com\/de\/team-member\/"},{"@type":"ListItem","position":3,"name":"Andrew Bozzelli"}]},{"@type":"WebSite","@id":"https:\/\/livingstonepartners.com\/de\/#website","url":"https:\/\/livingstonepartners.com\/de\/","name":"Livingstone Partners","description":"Deals Done Right.","publisher":{"@id":"https:\/\/livingstonepartners.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livingstonepartners.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/livingstonepartners.com\/de\/#organization","name":"Livingstone Partners","url":"https:\/\/livingstonepartners.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/livingstonepartners.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","contentUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","caption":"Livingstone Partners"},"image":{"@id":"https:\/\/livingstonepartners.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/team-member\/1336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/team-member"}],"about":[{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/types\/team-member"}],"version-history":[{"count":0,"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/team-member\/1336\/revisions"}],"acf:term":[{"embeddable":true,"taxonomy":"service","href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/service\/441"},{"embeddable":true,"taxonomy":"service","href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/service\/442"},{"embeddable":true,"taxonomy":"sector","href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/sector\/692"},{"embeddable":true,"taxonomy":"sector","href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/sector\/691"},{"embeddable":true,"taxonomy":"office","href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/office\/294"},{"embeddable":true,"taxonomy":"job-title","href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/job-title\/170"}],"wp:attachment":[{"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/media?parent=1336"}],"wp:term":[{"taxonomy":"job-title","embeddable":true,"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/job-title?post=1336"},{"taxonomy":"office","embeddable":true,"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/office?post=1336"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/sector?post=1336"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/livingstonepartners.com\/de\/wp-json\/wp\/v2\/service?post=1336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}