{"id":58533,"date":"2022-05-03T13:33:14","date_gmt":"2022-05-03T17:33:14","guid":{"rendered":"https:\/\/livingstagenew.wpenginepowered.com\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/"},"modified":"2022-05-03T13:33:14","modified_gmt":"2022-05-03T17:33:14","slug":"i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli","status":"publish","type":"insights","link":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/","title":{"rendered":"I professionisti di Livingstone continuano a crescere in nuovi ruoli"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>Livingstone rafforza la propria struttura con la nomina di due <strong data-start=\"63\" data-end=\"85\">Associate Director<\/strong> e di un <strong data-start=\"94\" data-end=\"107\">Associate<\/strong>, promuovendo <\/b><a href=\"https:\/\/livingstonepartners.com\/it\/team\/zakaria-marakbi\"><b>Zakaria Marakbi<\/b><\/a><b> e Henrik Lillieh\u00f6\u00f6k al ruolo di Associate Director ed Edward Herslow ad Associate.<\/b>&#13;<br>&#13;<br><a href=\"https:\/\/livingstonepartners.com\/it\/team\/zakaria-marakbi\"><strong>Zakaria Marakbi<\/strong><\/a> e <strong>Henrik Lillieh\u00f6\u00f6k<\/strong> fanno entrambi parte del team Livingstone di Stoccolma dal 2018.&#13;<br>&#13;<br>Nel corso della sua esperienza in Livingstone, <a href=\"https:\/\/livingstonepartners.com\/it\/team\/zakaria-marakbi\">Zakaria<\/a> ha partecipato a numerose operazioni in vari settori. Tra queste figurano la vendita di <a href=\"https:\/\/livingstonepartners.com\/it\/transactions\/livingstone-has-advised-accent-equity-on-the-sale-of-san-sac-group-to-french-company-sulo\">San Sac Group<\/a> (precedentemente societ\u00e0 in portafoglio di Accent Equity) alla societ\u00e0 francese Sulo, la vendita di <a href=\"https:\/\/livingstonepartners.com\/it\/transactions\/henry-schein-acquires-majority-interest-in-cliniclands-an-innovative-nordic-distributor\">Cliniclands<\/a> alla societ\u00e0 americana Henry Schein e la vendita di <a href=\"https:\/\/livingstonepartners.com\/it\/transactions\/livingstone-advised-ad-delivery-platform-adtoox-on-sale-to-peach-a-portfolio-company-of-inflexion\">Adtoox<\/a> a Peach (una societ\u00e0 in portafoglio di Inflexion Private Equity).&#13;<br>&#13;<br>Durante la sua permanenza in Livingstone, Henrik ha lavorato con aziende come <a href=\"https:\/\/livingstonepartners.com\/it\/transactions\/livingstone-advises-the-shareholders-of-biototal-on-mvi-majority-investment\">Biototal<\/a>, operante nel settore della nutrizione vegetale circolare con particolare attenzione al settore agricolo, e Modigo, leader svedese nella valutazione neuropsichiatrica e nel trattamento medico di pazienti affetti da ADHD.&#13;<br>&#13;<br><strong>Edward Herslow<\/strong> fa parte del team di Livingstone a Stoccolma dal 2020 e\u00a0ora viene promosso da Analyst ad Associate. Nel corso della sua esperienza in Livingstone ha partecipato alla vendita di <a href=\"https:\/\/livingstonepartners.com\/it\/transactions\/livingstone-has-advised-tm-konsult-on-sale-to-afry\">TM Konsult <\/a>ad AFRY e alla vendita di <a href=\"https:\/\/livingstonepartners.com\/it\/transactions\/livingstone-has-advised-vrdvskan-on-its-sale-to-storskogen\">V\u00e5rdv\u00e4skan<\/a>a Storskogen.&#13;<br>&#13;<br><em>\u201cAbbiamo avuto un anno molto intenso con un numero record di operazioni. Prevediamo che il livello di attivit\u00e0 rester\u00e0 elevato anche in futuro e stiamo lavorando per inserire nuovi Analyst, mentre allo stesso tempo osserviamo una forte crescita all\u2019interno dell\u2019organizzazione, con molti colleghi che stanno evolvendo nei loro ruoli, il che \u00e8 molto gratificante\u201d<\/em>, afferma <a href=\"https:\/\/livingstonepartners.com\/it\/team\/daniel-ohlsson\"><b>Daniel Ohlsson<\/b><\/a><b>, amministratore delegato di Livingstone a Stoccolma.<\/b>&#13;<br>&#13;<br>Daniel continua: <em>\u201cIl gruppo dei partner ha quindi deciso di apportare alcune modifiche e di promuovere Henrik Lillieh\u00f6\u00f6k e Zakaria Marakbi a Associate Director ed Edward Herslow ad Associate. Henrik, Zakaria ed Edward hanno tutti dimostrato grande impegno, assumendosi responsabilit\u00e0 significative nei loro ruoli e dimostrando la loro capacit\u00e0 di instaurare un rapporto di fiducia con i nostri clienti\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stiamo rafforzando ed espandendo il team internazionale di Livingstone con la nomina di due nuovi Associate Director e di un nuovo Associate.<\/p>\n","protected":false},"author":3,"featured_media":57697,"template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2741],"tags":[],"sector":[],"service":[],"class_list":["post-58533","insights","type-insights","status-publish","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I professionisti di Livingstone continuano a crescere in nuovi ruoli - Livingstone Partners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I professionisti di Livingstone continuano a crescere in nuovi ruoli - Livingstone Partners\" \/>\n<meta property=\"og:description\" content=\"Stiamo rafforzando ed espandendo il team internazionale di Livingstone con la nomina di due nuovi Associate Director e di un nuovo Associate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Livingstone Partners\" \/>\n<meta property=\"og:image\" content=\"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/zakariaCo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\\\/\",\"name\":\"I professionisti di Livingstone continuano a crescere in nuovi ruoli - Livingstone Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/zakariaCo.jpg\",\"datePublished\":\"2022-05-03T17:33:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/zakariaCo.jpg\",\"contentUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/zakariaCo.jpg\",\"width\":958,\"height\":696},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I professionisti di Livingstone continuano a crescere in nuovi ruoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/\",\"name\":\"Livingstone Partners\",\"description\":\"Deals Done Right.\",\"publisher\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#organization\",\"name\":\"Livingstone Partners\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"contentUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"caption\":\"Livingstone Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I professionisti di Livingstone continuano a crescere in nuovi ruoli - Livingstone Partners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/","og_locale":"it_IT","og_type":"article","og_title":"I professionisti di Livingstone continuano a crescere in nuovi ruoli - Livingstone Partners","og_description":"Stiamo rafforzando ed espandendo il team internazionale di Livingstone con la nomina di due nuovi Associate Director e di un nuovo Associate.","og_url":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/","og_site_name":"Livingstone Partners","og_image":[{"width":958,"height":696,"url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/zakariaCo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/","url":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/","name":"I professionisti di Livingstone continuano a crescere in nuovi ruoli - Livingstone Partners","isPartOf":{"@id":"https:\/\/livingstonepartners.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/#primaryimage"},"image":{"@id":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/#primaryimage"},"thumbnailUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/zakariaCo.jpg","datePublished":"2022-05-03T17:33:14+00:00","breadcrumb":{"@id":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/#primaryimage","url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/zakariaCo.jpg","contentUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/zakariaCo.jpg","width":958,"height":696},{"@type":"BreadcrumbList","@id":"https:\/\/livingstonepartners.com\/it\/insights\/i-professionisti-di-livingstone-continuano-a-crescere-in-nuovi-ruoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/livingstonepartners.com\/it\/"},{"@type":"ListItem","position":2,"name":"I professionisti di Livingstone continuano a crescere in nuovi ruoli"}]},{"@type":"WebSite","@id":"https:\/\/livingstonepartners.com\/it\/#website","url":"https:\/\/livingstonepartners.com\/it\/","name":"Livingstone Partners","description":"Deals Done Right.","publisher":{"@id":"https:\/\/livingstonepartners.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livingstonepartners.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/livingstonepartners.com\/it\/#organization","name":"Livingstone Partners","url":"https:\/\/livingstonepartners.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/livingstonepartners.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","contentUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","caption":"Livingstone Partners"},"image":{"@id":"https:\/\/livingstonepartners.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/insights\/58533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/types\/insights"}],"author":[{"embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/insights\/58533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/media\/57697"}],"wp:attachment":[{"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/media?parent=58533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/categories?post=58533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/tags?post=58533"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/sector?post=58533"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/service?post=58533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}