{"id":58553,"date":"2022-11-29T15:21:25","date_gmt":"2022-11-29T19:21:25","guid":{"rendered":"https:\/\/livingstagenew.wpenginepowered.com\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/"},"modified":"2026-07-27T08:26:15","modified_gmt":"2026-07-27T12:26:15","slug":"e-farm-il-marketplace-online-per-le-macchine-agricole","status":"publish","type":"insights","link":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/","title":{"rendered":"E-Farm: il marketplace online per le macchine agricole"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nell\u2019edizione Autunno \/ Inverno 2022 di&nbsp;<em>MATURUSAKTUELL<\/em>&nbsp;\u00e8 presente un case study dedicato a&nbsp;<a href=\"https:\/\/e-farm.com\/de\/\">E-Farm<\/a>, piattaforma online per la compravendita di macchinari agricoli usati.&nbsp;<a href=\"https:\/\/livingstonepartners.com\/it\/team\/michael-westhoven\">Michael Westhoven<\/a>,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Partner di Livingstone D\u00fcsseldorf, ha supportato E-Farm nella ricerca di soluzioni di finanziamento alternative per l\u2019acquisizione di macchine agricole, come alternativa al tradizionale modello di intermediazione. L\u2019azienda ha scelto l\u2019Asset Based Credit (ABC) come soluzione di investimento, in quanto consente di utilizzare asset di valore come garanzia del finanziamento. Questo approccio tutela la performance finanziaria dell\u2019azienda e, in generale, permette di ottenere un rapporto loan-to-value pi\u00f9 elevato rispetto a un finanziamento tradizionale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leggi l\u2019articolo completo su\u00a0<a href=\"https:\/\/www.maturus-finance.com\/files\/aktuelles\/downloads\/Maturus%20aktuell%20Winter%202022.pdf\" type=\"link\" id=\"https:\/\/www.maturus-finance.com\/files\/aktuelles\/downloads\/Maturus%20aktuell%20Winter%202022.pdf\">MATURUSAKTUELL \/\/ Fall \/ Winter 2022 issue<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019edizione Autunno \/ Inverno 2022 di MATURUSAKTUELL \u00e8 presente un case study dedicato a E-Farm, piattaforma online per la compravendita di macchinari agricoli usati.<\/p>\n","protected":false},"author":3,"featured_media":57717,"template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[],"tags":[],"sector":[],"service":[],"class_list":["post-58553","insights","type-insights","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>E-Farm: il marketplace online per le macchine agricole - Livingstone Partners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-Farm: il marketplace online per le macchine agricole\" \/>\n<meta property=\"og:description\" content=\"Nell\u2019edizione Autunno \/ Inverno 2022 di MATURUSAKTUELL \u00e8 presente un case study dedicato a E-Farm, piattaforma online per la compravendita di macchinari agricoli usati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/\" \/>\n<meta property=\"og:site_name\" content=\"Livingstone Partners\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-27T12:26:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/Livingstone_Tractor-e1669732353509.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/e-farm-il-marketplace-online-per-le-macchine-agricole\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/e-farm-il-marketplace-online-per-le-macchine-agricole\\\/\",\"name\":\"E-Farm: il marketplace online per le macchine agricole - Livingstone Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/e-farm-il-marketplace-online-per-le-macchine-agricole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/e-farm-il-marketplace-online-per-le-macchine-agricole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Livingstone_Tractor-e1669732353509.jpg\",\"datePublished\":\"2022-11-29T19:21:25+00:00\",\"dateModified\":\"2026-07-27T12:26:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/e-farm-il-marketplace-online-per-le-macchine-agricole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/e-farm-il-marketplace-online-per-le-macchine-agricole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/e-farm-il-marketplace-online-per-le-macchine-agricole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Livingstone_Tractor-e1669732353509.jpg\",\"contentUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Livingstone_Tractor-e1669732353509.jpg\",\"width\":550,\"height\":369},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/insights\\\/e-farm-il-marketplace-online-per-le-macchine-agricole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-Farm: il marketplace online per le macchine agricole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/\",\"name\":\"Livingstone Partners\",\"description\":\"Deals Done Right.\",\"publisher\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#organization\",\"name\":\"Livingstone Partners\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"contentUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"caption\":\"Livingstone Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/livingstone\\\/\"],\"description\":\"Livingstone is an independent, global M&A and debt advisory firm with a proven track record of delivering exceptional outcomes for private and public businesses and private equity investors.\",\"email\":\"marketing@livingstonepartners.com\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"E-Farm: il marketplace online per le macchine agricole - Livingstone Partners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/","og_locale":"it_IT","og_type":"article","og_title":"E-Farm: il marketplace online per le macchine agricole","og_description":"Nell\u2019edizione Autunno \/ Inverno 2022 di MATURUSAKTUELL \u00e8 presente un case study dedicato a E-Farm, piattaforma online per la compravendita di macchinari agricoli usati.","og_url":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/","og_site_name":"Livingstone Partners","article_modified_time":"2026-07-27T12:26:15+00:00","og_image":[{"width":550,"height":369,"url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/Livingstone_Tractor-e1669732353509.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/","url":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/","name":"E-Farm: il marketplace online per le macchine agricole - Livingstone Partners","isPartOf":{"@id":"https:\/\/livingstonepartners.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/#primaryimage"},"image":{"@id":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/#primaryimage"},"thumbnailUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/Livingstone_Tractor-e1669732353509.jpg","datePublished":"2022-11-29T19:21:25+00:00","dateModified":"2026-07-27T12:26:15+00:00","breadcrumb":{"@id":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/#primaryimage","url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/Livingstone_Tractor-e1669732353509.jpg","contentUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/Livingstone_Tractor-e1669732353509.jpg","width":550,"height":369},{"@type":"BreadcrumbList","@id":"https:\/\/livingstonepartners.com\/it\/insights\/e-farm-il-marketplace-online-per-le-macchine-agricole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/livingstonepartners.com\/it\/"},{"@type":"ListItem","position":2,"name":"E-Farm: il marketplace online per le macchine agricole"}]},{"@type":"WebSite","@id":"https:\/\/livingstonepartners.com\/it\/#website","url":"https:\/\/livingstonepartners.com\/it\/","name":"Livingstone Partners","description":"Deals Done Right.","publisher":{"@id":"https:\/\/livingstonepartners.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livingstonepartners.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/livingstonepartners.com\/it\/#organization","name":"Livingstone Partners","url":"https:\/\/livingstonepartners.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/livingstonepartners.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","contentUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","caption":"Livingstone Partners"},"image":{"@id":"https:\/\/livingstonepartners.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/livingstone\/"],"description":"Livingstone is an independent, global M&A and debt advisory firm with a proven track record of delivering exceptional outcomes for private and public businesses and private equity investors.","email":"marketing@livingstonepartners.com"}]}},"_links":{"self":[{"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/insights\/58553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/types\/insights"}],"author":[{"embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/insights\/58553\/revisions"}],"predecessor-version":[{"id":88961,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/insights\/58553\/revisions\/88961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/media\/57717"}],"wp:attachment":[{"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/media?parent=58553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/categories?post=58553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/tags?post=58553"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/sector?post=58553"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/livingstonepartners.com\/it\/wp-json\/wp\/v2\/service?post=58553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}