{"id":976,"date":"2026-05-06T09:37:19","date_gmt":"2026-05-06T13:37:19","guid":{"rendered":"https:\/\/livingstagenew.wpenginepowered.com\/team-member\/remco-goes-nl\/"},"modified":"2026-05-06T10:27:04","modified_gmt":"2026-05-06T14:27:04","slug":"remco-goes","status":"publish","type":"team-member","link":"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/","title":{"rendered":"Remco Goes"},"content":{"rendered":"\n<p>Remco started his career in 2007 at Deloitte Corporate Finance where he worked on over 60 M&amp;A engagements, ranging from sell- and buy-side advisory to valuations, corporate carve-outs, and capital raises. <\/p><p>During this time Remco built a strong network across leading Private Equity and Venture Capital houses investing in the Benelux, leading (multi)nationals, and fast-growing technology companies.<\/p><p><strong>Education:<\/strong><\/p><ul><li><p>Erasmus University of Rotterdam<\/p><\/li><li><p>University of Groningen<\/p><\/li><\/ul>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"job-title":[120,120],"office":[],"sector":[605,605],"service":[429,429],"class_list":["post-976","team-member","type-team-member","status-publish","hentry","job-title-executive-assistant-nl","sector-generation-assets-renewables-upstream","service-debt-advisory"],"acf":{"headshot":43341,"headshot_alt":43342,"position":2,"job_title":127,"offices":[264],"email":"goes@livingstonebenelux.com","phone":"+31 6 1234 4578","mobile_phone":"","connect":"https:\/\/www.linkedin.com\/in\/remco-goes\/","sectors":[577,578,611,579,580,581],"services":[429,428,427,430]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Remco Goes - Livingstone Partners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remco Goes - Livingstone Partners\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/\" \/>\n<meta property=\"og:site_name\" content=\"Livingstone Partners\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T14:27:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/team-member\\\/remco-goes\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/team-member\\\/remco-goes\\\/\",\"name\":\"Remco Goes - Livingstone Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/#website\"},\"datePublished\":\"2026-05-06T13:37:19+00:00\",\"dateModified\":\"2026-05-06T14:27:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/team-member\\\/remco-goes\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/team-member\\\/remco-goes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/team-member\\\/remco-goes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team Members\",\"item\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/team-member\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Remco Goes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/\",\"name\":\"Livingstone Partners\",\"description\":\"Deals Done Right.\",\"publisher\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/#organization\",\"name\":\"Livingstone Partners\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"contentUrl\":\"https:\\\/\\\/livingstonepartners.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo_livingstone.svg\",\"caption\":\"Livingstone Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/livingstonepartners.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remco Goes - Livingstone Partners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/","og_locale":"nl_NL","og_type":"article","og_title":"Remco Goes - Livingstone Partners","og_url":"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/","og_site_name":"Livingstone Partners","article_modified_time":"2026-05-06T14:27:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/","url":"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/","name":"Remco Goes - Livingstone Partners","isPartOf":{"@id":"https:\/\/livingstonepartners.com\/nl\/#website"},"datePublished":"2026-05-06T13:37:19+00:00","dateModified":"2026-05-06T14:27:04+00:00","breadcrumb":{"@id":"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/livingstonepartners.com\/nl\/team-member\/remco-goes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/livingstonepartners.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Team Members","item":"https:\/\/livingstonepartners.com\/nl\/team-member\/"},{"@type":"ListItem","position":3,"name":"Remco Goes"}]},{"@type":"WebSite","@id":"https:\/\/livingstonepartners.com\/nl\/#website","url":"https:\/\/livingstonepartners.com\/nl\/","name":"Livingstone Partners","description":"Deals Done Right.","publisher":{"@id":"https:\/\/livingstonepartners.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livingstonepartners.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/livingstonepartners.com\/nl\/#organization","name":"Livingstone Partners","url":"https:\/\/livingstonepartners.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/livingstonepartners.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","contentUrl":"https:\/\/livingstonepartners.com\/wp-content\/uploads\/2026\/05\/logo_livingstone.svg","caption":"Livingstone Partners"},"image":{"@id":"https:\/\/livingstonepartners.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/team-member\/976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/team-member"}],"about":[{"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/types\/team-member"}],"version-history":[{"count":0,"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/team-member\/976\/revisions"}],"acf:term":[{"embeddable":true,"taxonomy":"service","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/service\/430"},{"embeddable":true,"taxonomy":"service","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/service\/427"},{"embeddable":true,"taxonomy":"service","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/service\/428"},{"embeddable":true,"taxonomy":"service","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/service\/429"},{"embeddable":true,"taxonomy":"sector","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/sector\/580"},{"embeddable":true,"taxonomy":"sector","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/sector\/579"},{"embeddable":true,"taxonomy":"sector","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/sector\/611"},{"embeddable":true,"taxonomy":"sector","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/sector\/578"},{"embeddable":true,"taxonomy":"sector","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/sector\/577"},{"embeddable":true,"taxonomy":"office","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/office\/264"},{"embeddable":true,"taxonomy":"job-title","href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/job-title\/127"}],"wp:attachment":[{"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/media?parent=976"}],"wp:term":[{"taxonomy":"job-title","embeddable":true,"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/job-title?post=976"},{"taxonomy":"office","embeddable":true,"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/office?post=976"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/sector?post=976"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/livingstonepartners.com\/nl\/wp-json\/wp\/v2\/service?post=976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}